{"id":11505,"date":"2022-08-10T13:07:57","date_gmt":"2022-08-10T12:07:57","guid":{"rendered":"https:\/\/nkyeremunews.com\/?p=11505"},"modified":"2022-08-10T13:20:20","modified_gmt":"2022-08-10T12:20:20","slug":"i-like-hearts-of-oak-colours","status":"publish","type":"post","link":"https:\/\/nkyeremunews.com\/index.php\/2022\/08\/10\/i-like-hearts-of-oak-colours\/","title":{"rendered":"I Like Hearts Of Oak Colours!"},"content":{"rendered":"<p>I like Heart of Oak colours more than anything else. I wish they become the best club in Africa one day.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-11507\" src=\"https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.04.44-PM-300x215.jpeg\" alt=\"\" width=\"300\" height=\"215\" srcset=\"https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.04.44-PM-300x215.jpeg 300w, https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.04.44-PM.jpeg 477w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/> <img decoding=\"async\" class=\"alignnone size-medium wp-image-11508\" src=\"https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.03.37-PM-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.03.37-PM-225x300.jpeg 225w, https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.03.37-PM-315x420.jpeg 315w, https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/WhatsApp-Image-2022-08-10-at-12.03.37-PM.jpeg 493w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I like Heart of Oak colours more than anything else. I wish they become the<\/p>\n","protected":false},"author":1,"featured_media":11509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,1],"tags":[],"aioseo_notices":[],"featured_image_urls":{"full":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-scaled.jpg",2560,1235,false],"thumbnail":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-150x150.jpg",150,150,true],"medium":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-300x145.jpg",300,145,true],"medium_large":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-768x371.jpg",640,309,true],"large":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-1024x494.jpg",640,309,true],"1536x1536":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-1536x741.jpg",1536,741,true],"2048x2048":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-2048x988.jpg",2048,988,true],"chromenews-featured":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-scaled.jpg",1024,494,false],"chromenews-large":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-scaled.jpg",825,398,false],"chromenews-medium":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2022\/08\/BeFunky-collage-2022-08-10T120644.454-scaled.jpg",590,285,false]},"author_info":{"display_name":"nkyeremunews","author_link":"https:\/\/nkyeremunews.com\/index.php\/author\/nkyeremunews\/"},"category_info":"<a href=\"https:\/\/nkyeremunews.com\/index.php\/category\/entertainment\/\" rel=\"category tag\">Entertainment<\/a> <a href=\"https:\/\/nkyeremunews.com\/index.php\/category\/uncategorised\/\" rel=\"category tag\">Nkyeremu<\/a>","tag_info":"Nkyeremu","comment_count":"0","_links":{"self":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/posts\/11505"}],"collection":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/comments?post=11505"}],"version-history":[{"count":0,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/posts\/11505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/media\/11509"}],"wp:attachment":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/media?parent=11505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/categories?post=11505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/tags?post=11505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}