{"id":17787,"date":"2023-01-06T14:07:01","date_gmt":"2023-01-06T14:07:01","guid":{"rendered":"https:\/\/nkyeremunews.com\/?p=17787"},"modified":"2023-01-06T14:07:01","modified_gmt":"2023-01-06T14:07:01","slug":"i-need-the-deserved-finger-ring-too","status":"publish","type":"post","link":"https:\/\/nkyeremunews.com\/index.php\/2023\/01\/06\/i-need-the-deserved-finger-ring-too\/","title":{"rendered":"I Need The Deserved Finger Ring Too!"},"content":{"rendered":"<p>I need the deserved finger ring too!<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-medium wp-image-17788\" src=\"https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-06-at-12.41.38-PM-4-241x300.jpeg\" alt=\"\" width=\"241\" height=\"300\" srcset=\"https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-06-at-12.41.38-PM-4-241x300.jpeg 241w, https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-06-at-12.41.38-PM-4-696x866.jpeg 696w, https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-06-at-12.41.38-PM-4-338x420.jpeg 338w, https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/WhatsApp-Image-2023-01-06-at-12.41.38-PM-4.jpeg 701w\" sizes=\"(max-width: 241px) 100vw, 241px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I need the deserved finger ring too!<\/p>\n","protected":false},"author":1,"featured_media":17789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,1],"tags":[],"aioseo_notices":[],"featured_image_urls":{"full":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-scaled.jpg",2560,1107,false],"thumbnail":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-150x150.jpg",150,150,true],"medium":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-300x130.jpg",300,130,true],"medium_large":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-768x332.jpg",640,277,true],"large":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-1024x443.jpg",640,277,true],"1536x1536":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-1536x664.jpg",1536,664,true],"2048x2048":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-2048x886.jpg",2048,886,true],"chromenews-featured":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-scaled.jpg",1024,443,false],"chromenews-large":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-scaled.jpg",825,357,false],"chromenews-medium":["https:\/\/nkyeremunews.com\/wp-content\/uploads\/2023\/01\/BeFunky-collage-2023-01-06T140553.035-scaled.jpg",590,255,false]},"author_info":{"display_name":"nkyeremunews","author_link":"https:\/\/nkyeremunews.com\/index.php\/author\/nkyeremunews\/"},"category_info":"<a href=\"https:\/\/nkyeremunews.com\/index.php\/category\/entertainment\/\" rel=\"category tag\">Entertainment<\/a> <a href=\"https:\/\/nkyeremunews.com\/index.php\/category\/uncategorised\/\" rel=\"category tag\">Nkyeremu<\/a>","tag_info":"Nkyeremu","comment_count":"180","_links":{"self":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/posts\/17787"}],"collection":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/comments?post=17787"}],"version-history":[{"count":0,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/posts\/17787\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/media\/17789"}],"wp:attachment":[{"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/media?parent=17787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/categories?post=17787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nkyeremunews.com\/index.php\/wp-json\/wp\/v2\/tags?post=17787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}